{"id":5975,"date":"2024-06-16T01:19:23","date_gmt":"2024-06-16T01:19:23","guid":{"rendered":"https:\/\/reservaloscedros.org\/?page_id=5975"},"modified":"2026-08-24T13:56:58","modified_gmt":"2026-08-24T13:56:58","slug":"plants","status":"publish","type":"page","link":"https:\/\/reservaloscedros.org\/es\/plants\/","title":{"rendered":"Plantas"},"content":{"rendered":"<p><header class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: var(--awb-color2);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion-flex-column fusion-animated\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:10px!important; margin-right:!important;margin-bottom:28px!important;margin-left:!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:5px!important; margin-right:!important;margin-bottom:0px!important; margin-left:!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-no-small-visibility fusion-no-medium-visibility fusion-title-text fusion-title-size-two\" style=\"font-size:48px;margin-top:10px;margin-bottom:28px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Epilogue&quot;;font-weight:600;margin:0;font-size:1em;letter-spacing:var(--awb-typography1-letter-spacing);text-transform:var(--awb-typography1-text-transform);color:#2b2b2b;--fontSize:48;line-height:1.2;\">PLANTS<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-2{margin-top:10px!important; margin-right:!important;margin-bottom:28px!important;margin-left:!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-2{margin-top:5px!important; margin-right:!important;margin-bottom:0px!important; margin-left:!important;}}<\/style><div class=\"fusion-title title fusion-title-2 fusion-no-large-visibility fusion-title-text fusion-title-size-two\" style=\"font-size:36px;margin-top:10px;margin-bottom:28px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;font-size:1em;text-transform:capitalize;--fontSize:36;line-height:var(--awb-typography1-line-height);\"><strong>PLANTS<\/strong><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"font-size:18px;line-height:1.7;letter-spacing:0px;text-transform:var(--awb-typography4-text-transform);color:#2b2b2b;font-family:&quot;Inter&quot;;font-weight:400;margin-bottom:30px;\"><p>Abundant tree species at Los Cedros Reserve include Copal, Madro\u00f1o, Avocatillo, Strangler Fig and Clusia, while the endangered Cedars that give the reserve its name are less numerous. The number of tree species per hectare is very high, estimated to be as many as 400\/ha.<\/p>\n<\/div><div ><style>.fusion-body .fusion-button.button-1 .fusion-button-text{color:var(--awb-color1);text-transform:var(--awb-typography3-text-transform);}.fusion-body .fusion-button.button-1{border-color:var(--awb-color1);border-radius:0 0 0 0;background:var(--awb-color4);font-size:15px;line-height:1.2;padding-top:18px;padding-bottom:18px;letter-spacing:0px;font-family:\"Inter\";font-weight:500;}.fusion-body .fusion-button.button-1 i,.fusion-body .fusion-button.button-1:hover .fusion-button-text,.fusion-body .fusion-button.button-1:hover i,.fusion-body .fusion-button.button-1:focus .fusion-button-text,.fusion-body .fusion-button.button-1:focus i,.fusion-body .fusion-button.button-1:active .fusion-button-text,.fusion-body .fusion-button.button-1:active i{color:var(--awb-color1);}.fusion-body .fusion-button.button-1:hover,.fusion-body .fusion-button.button-1:active,.fusion-body .fusion-button.button-1:focus{border-color:var(--awb-color1);background:var(--awb-color5);}<\/style><a class=\"fusion-button button-flat fusion-button-default-size button-custom button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/drive.google.com\/drive\/folders\/10VHE0fN5HRtDYuvYf5XTxk-JTFAPy5SO?usp=sharing\" style=\"margin-top:10px;\"><i class=\"fa-download fas button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text\">Download List<\/span><\/a><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:47% !important;margin-top : 43px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 13.276595744681%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 4.0851063829787%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;padding-left : 40px !important;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 1;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-right : 0px !important;margin-right : 0%;padding-left : 0px !important;margin-left : 1.92%;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\" md-text-align-center\"><style>@media only screen and (max-width:1024px) {.fusion-imageframe.imageframe-1{ margin-top : 20px;}}<\/style><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none imagen-full-width\"><img decoding=\"async\" width=\"225\" height=\"300\" title=\"2025-06-05 15.33.59\" src=\"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-scaled.webp\" data-orig-src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-225x300.webp\" alt class=\"lazyload img-responsive wp-image-6534\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%272560%27%20viewBox%3D%270%200%201920%202560%27%3E%3Crect%20width%3D%271920%27%20height%3D%272560%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-9x12.webp 9w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-200x267.webp 200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-225x300.webp 225w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-400x533.webp 400w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-600x800.webp 600w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-768x1024.webp 768w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-800x1067.webp 800w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-1152x1536.webp 1152w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-1200x1600.webp 1200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-1536x2048.webp 1536w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2026\/08\/2025-06-05-15.33.59-scaled.webp 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:53% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 3.622641509434%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 3.622641509434%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-right : 40px !important;margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;margin-bottom : 50px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-right : 0px !important;margin-right : 0%;padding-left : 0px !important;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 42px;padding-bottom : 130px;margin-bottom : 0px;padding-left : 38px;}@media only screen and (max-width:1024px) {.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 45px;padding-bottom : 72px;}}@media only screen and (max-width:640px) {.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-left : 0px;}}<\/style><\/header><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-3{margin-top:75px!important; margin-right:!important;margin-bottom:0px!important;margin-left:!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-3{margin-top:5px!important; margin-right:!important;margin-bottom:0px!important; margin-left:!important;}}<\/style><div class=\"fusion-title title fusion-title-3 fusion-title-text fusion-title-size-one\" style=\"margin-top:75px;margin-bottom:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h1 class=\"title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:var(--awb-typography1-font-family);font-weight:var(--awb-typography1-font-weight);font-style:var(--awb-typography1-font-style);margin:0;text-transform:capitalize;--fontSize:60;line-height:var(--awb-typography1-line-height);\"><h2>List of Plant Species at Los Cedros &#8211; not including orchids<\/h2><\/h1><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-4{margin-top:0px!important; margin-right:!important;margin-bottom:50px!important;margin-left:!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-4{margin-top:5px!important; margin-right:!important;margin-bottom:0px!important; margin-left:!important;}}<\/style><div class=\"fusion-title title fusion-title-4 fusion-title-text fusion-title-size-three\" style=\"margin-top:0px;margin-bottom:50px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h3 class=\"title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:var(--awb-typography1-font-family);font-weight:var(--awb-typography1-font-weight);font-style:var(--awb-typography1-font-style);margin:0;text-transform:capitalize;--fontSize:25;line-height:var(--awb-typography1-line-height);\">(Better on desktop)<\/h3><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:var(--awb-color3);\"><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-3{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-3 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\">\n<table id=\"tablepress-3\" class=\"tablepress tablepress-id-3\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Photo URL<\/th><th class=\"column-2\">Scientific name<\/th><th class=\"column-3\">Family<\/th><th class=\"column-4\">Growth form<\/th><th class=\"column-5\">Ecuador Red List<\/th><th class=\"column-6\">IUCN Status<\/th><th class=\"column-7\">Endemic?<\/th><th class=\"column-8\">Record or Publication<\/th><th class=\"column-9\">Voucher Collection or Botanist<\/th><th class=\"column-10\">Date Assessed<\/th><th class=\"column-11\">Notes<\/th><td class=\"column-12\"><\/td>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Abarema sp.<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Acalypha diversifolia<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Miranda et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=171997&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Permanent plot and A 50 m del R\u00edo Los Cedros por el camino que lleva al Sendero Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/109771834<\/td><td class=\"column-2\">Adelobotrys<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat: Exe<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\">might be a new species<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9993081<\/td><td class=\"column-2\">Adiantum concinnum<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9735898<\/td><td class=\"column-2\">Adiantum urophyllum<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Aegiphila alba<\/td><td class=\"column-3\">Verbenaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2961892<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Agouticarpa grandistipula<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Shrub<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947044<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Aiouea montana (syn=Cinnamomum triplinerve)<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/28\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117465897<\/td><td class=\"column-2\">Aiphanes bicornis<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-9\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Aiphanes chiribogensis<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117467749<\/td><td class=\"column-2\">Aiphanes erinacea<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">(NT)<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-9\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">NT according to Tropicos but not in Ecuador Red list<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9805422<\/td><td class=\"column-2\">Alansmia cultrata<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alchornea cf. grandis<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alchornea cf. leptogyna<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Allophylus floribundus<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/730589<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Allophylus incanus<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">8\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Allophylus punctatus<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alloplectus andinus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Freiberg, 1997<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alloplectus dodsonii<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Freiberg, 1997<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/55563497<\/td><td class=\"column-2\">Alloplectus oblongicalyx<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362422<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alloplectus penduliflorus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg, 1997; Clark, 2009<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364910<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Type locality is Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alloplectus sprucei<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg, 1997; Clark, 2009<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364660<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alloplectus tetragonoides<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg, 1997<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alloplectus teuscheri<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362644<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9736088<\/td><td class=\"column-2\">Alsophila cuspidata (syn=Cyathea cuspidata)<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alsophila erinacea<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008; Mariscal, Thomas et. al. 2021<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/608345<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alsophila incana<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Alternanthera mexicana<\/td><td class=\"column-3\">Amaranthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=139156&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">A 50 m del R\u00edo los Cedros por el camino que lleva al Sendero Observator\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Aniba cf. hostmanniana<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Annona dolichopetala<\/td><td class=\"column-3\">Annonaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Annona edulis<\/td><td class=\"column-3\">Annonaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377190&amp;clid=0<\/td><td class=\"column-10\">11\/17\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117469788<\/td><td class=\"column-2\">Annona neglecta<\/td><td class=\"column-3\">Annonaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat: Thomas Couvreur<\/td><td class=\"column-9\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117469282<\/td><td class=\"column-2\">Annona papilionella<\/td><td class=\"column-3\">Annonaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat: Thomas Couvreur<\/td><td class=\"column-9\">ID by Heimo Rainer<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthopteropsis<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364892<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthopterus cuneatus <\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5776557&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero observatorio (sw of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium amoenum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947027<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium ceronii<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Croat TB, Ling\u00e1n J, Hayworth D. 2005. A new section of Anthurium, Sect. Decurrentia\u2014Revision of the Anthurium decurrens Poeppig complex in Amazonia. Rodrigu\u00e9sia 56(88): 15-30.<\/td><td class=\"column-9\">Tipaz et al. 771 (QCNE)<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium corrugatum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6139991&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero camino del oso (north of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium draconopterum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362658<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium incomptum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362596<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium mindense<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen A. Mariscal<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/100735098<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium ovatifolium<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">semi woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362662<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium pucayacuense<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Croat, 2008<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium pulverulentum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946667<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium striatipes<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364916<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium toisanense<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362543<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Anthurium tonduzii<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362603<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41154197<\/td><td class=\"column-2\">Aphelandra chamissoniana<\/td><td class=\"column-3\">Acanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Aphelandra pepe-parodii<\/td><td class=\"column-3\">Acanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364802<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Arachnothryx reflexa<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947465<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">https:\/\/www.flickr.com\/photos\/andreaskay\/8603048522\/in\/album-72157629132785818\/<\/td><td class=\"column-2\">Ardisia websteri<\/td><td class=\"column-3\">Myrsinaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9805285<\/td><td class=\"column-2\">Ascogrammitis anfractuosa (syn=Terpsichore anfractuosa)<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9752721<\/td><td class=\"column-2\">Asplenium cuspidatum<\/td><td class=\"column-3\">Aspleniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">Endara, L. https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/606521<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9782175<\/td><td class=\"column-2\">Asplenium dissectum<\/td><td class=\"column-3\">Aspleniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9782051<\/td><td class=\"column-2\">Asplenium fragrans<\/td><td class=\"column-3\">Aspleniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Asplenium pteropus<\/td><td class=\"column-3\">Aspleniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947124<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9782069<\/td><td class=\"column-2\">Asplenium radicans<\/td><td class=\"column-3\">Aspleniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Asplenium rutaceum<\/td><td class=\"column-3\">Aspleniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S. et al. https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/607179<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Asplundia albicarpa<\/td><td class=\"column-3\">Cyclanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947119<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Asplundia vagans<\/td><td class=\"column-3\">Cyclanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=144037&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9736152<\/td><td class=\"column-2\">Austroblechnum divergens (syn=Blechnum divergens)<\/td><td class=\"column-3\">Blechnaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9812083<\/td><td class=\"column-2\">Austroblechnum wardiae (syn=Blechnum wardiae)<\/td><td class=\"column-3\">Blechnaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Axinaea sp.<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362699<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48974051<\/td><td class=\"column-2\">Bactris gasipaes var. chichagui<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">(VU)<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-9\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">VU according to Tropicos but not in Ecuador Red list or IUCN<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Bactris setulosa<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">1\/1\/1998<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Banara guianensis<\/td><td class=\"column-3\">Salicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946642<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Banara regia<\/td><td class=\"column-3\">Salicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946637<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Banara riparia<\/td><td class=\"column-3\">Salicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Barleria micans<\/td><td class=\"column-3\">Acanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Begonia glabra<\/td><td class=\"column-3\">Begoniaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946746<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/51637729<\/td><td class=\"column-2\">Begonia parviflora<\/td><td class=\"column-3\">Begoniaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946678<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/51637728<\/td><td class=\"column-2\">Begonia tiliifolia<\/td><td class=\"column-3\">Begoniaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Tebbit, 2017<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Beilschmiedia alloiophylla<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947070<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Beilschmiedia costaricensis<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947070<\/td><td class=\"column-10\">10\/1\/2020<\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Beilschmiedia pendula<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6244350&amp;clid=0<\/td><td class=\"column-10\">3\/29\/2019<\/td><td class=\"column-11\">sendero el observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Beilschmiedia tovarensis<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Bertiera guianensis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Besleria angustiflora<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">M. Freiberg<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/674456<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/bit<\/td><td class=\"column-2\">Besleria solanoides<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2104954&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Billia rosea<\/td><td class=\"column-3\">Hippocastanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/42393958<\/td><td class=\"column-2\">Blakea subconnata<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/42393958<\/td><td class=\"column-2\">Blechnum occidentale<\/td><td class=\"column-3\">Blechnaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Boehmeria caudata<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Bomarea pardina<\/td><td class=\"column-3\">Alstroemeriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=163310&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Borojoa sp.<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Bromelia karatas<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Brosimum alicastrum<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6277250&amp;clid=0<\/td><td class=\"column-10\">11\/23\/2021<\/td><td class=\"column-11\">sendero y de la cascada-bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Brosimum sp.<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2952653<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Parcela permanente de inventario de una hect\u00e1rea de bosque<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Brosmium utile<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">speciemen Vargas<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5824902&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Parcela permanente de inventario de una hect\u00e1rea de bosque<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/52303803<\/td><td class=\"column-2\">Browallia americana<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat: E. Obando<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Browallia sp.<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-93\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Brunellia acostae<\/td><td class=\"column-3\">Brunelliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">1\/1\/1998<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-94\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Brunellia comocladifolia<\/td><td class=\"column-3\">Brunelliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-95\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Brunellia intermis<\/td><td class=\"column-3\">Brunelliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6366686&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero estacion<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-96\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Burmeistera crispiloba<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Leon-Yanez et al., 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-97\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41851582<\/td><td class=\"column-2\">Burmeistera cyclostigma<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Muchhala<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/651905<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-98\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Burmeistera cylindrocarpa<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Muchhala<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/526870<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-99\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Burmeistera lutosa<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364641<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-100\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/148837659<\/td><td class=\"column-2\">Burmeistera multiflora<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Ulsterbotany<\/td><td class=\"column-9\">https:\/\/www.inaturalist.org\/observations\/148837659<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-101\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41154279<\/td><td class=\"column-2\">Burmeistera pterifolia<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Policha<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-102\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Calatola costaricensis<\/td><td class=\"column-3\">Icacinaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2957592<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Y de la Cascada-Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-103\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Calliandra pittieri<\/td><td class=\"column-3\">Fabaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362711<\/td><td class=\"column-10\">6\/19\/2018<\/td><td class=\"column-11\">Sendero de las Cascadas (1-2 km west of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-104\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Campelia zanonia<\/td><td class=\"column-3\">Commelinaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6552880&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-105\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Campyloneurum brevifolium<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947374<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Y de Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-106\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Campyloneurum sphenoides (Campyloneurum wercklei)<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-107\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Capparidastrum macrophyllum<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-108\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Capparis sp.<\/td><td class=\"column-3\">Capparaceae<\/td><td class=\"column-4\">?<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-109\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Capsicum geminifolium<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946761<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-110\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48045079<\/td><td class=\"column-2\">Capsicum lycianthoides<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-111\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Carapa megistocarpa<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947392<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-112\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Carica<\/td><td class=\"column-3\">Caricaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362537<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-113\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Caryodaphnopsis theobromifolia<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2952629<\/td><td class=\"column-10\">5\/7\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-114\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Casearia cajambrensis<\/td><td class=\"column-3\">Flacourtiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">8\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-115\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/109762925<\/td><td class=\"column-2\">Casearia sylvestris<\/td><td class=\"column-3\">Salicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-116\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41317776<\/td><td class=\"column-2\">Cavendishia grandifolia<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">11\/20\/2018<\/td><td class=\"column-10\">11\/20\/2018<\/td><td class=\"column-11\">main trail<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-117\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cavendishia micayensis<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6324941&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero camino del oso (north of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-118\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41189510<\/td><td class=\"column-2\">Cavendishia nobilis var. capitata<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Policha<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-119\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cecropia andina<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-120\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cecropia ficifolia<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008;  Mariscal, Thomas et. al. 2021<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375881&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-121\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cecropia maxima<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Berg et al. 2005.<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-122\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48041591<\/td><td class=\"column-2\">Cecropia reticulata<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008;  Mariscal, Thomas et. al. 2021<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-123\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cedrela odorata<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Shanee, 2007.; Wilson &amp; Rhemtulla 2016.<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">3\/23\/2017<\/td><td class=\"column-11\">Which Taxon this is is not very clear<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-124\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Centradeniastrum album<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362573<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-125\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/42173872<\/td><td class=\"column-2\">Centropogon solanifolius<\/td><td class=\"column-3\">Campanulaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-126\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cestrum megalophyllum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375859&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-127\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cestrum microcalyx<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946646<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-128\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cestrum schlechtendalii<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946645<\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-129\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117466532<\/td><td class=\"column-2\">Chamaedorea linearis<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">(NT)<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-9\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">NT according to Tropicos but not in Ecuador Red list<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-130\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Chamaedorea pinnatifrons<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=143462&amp;clid=0<\/td><td class=\"column-10\">5\/6\/2014<\/td><td class=\"column-11\">Colecciones generales de \u00e1rea en regeneraci\u00f3n con presencia de gramalote.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-131\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Chrysochlamys columbiana<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-132\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41455061<\/td><td class=\"column-2\">Chrysochlamys dependens<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729383<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-133\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Chrysophyllum aff. venezuelanense<\/td><td class=\"column-3\">Sapotaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-134\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Chrysophyllum cf. argenteum<\/td><td class=\"column-3\">Sapotaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-135\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Chrysophyllum manaosense<\/td><td class=\"column-3\">Sapotaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-136\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cissus<\/td><td class=\"column-3\">Vitaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364764<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-137\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Citronella cf. ilicifolia<\/td><td class=\"column-3\">Cardiopteridaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-138\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clarisia biflora<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2952634<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-139\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clavija eggersiana<\/td><td class=\"column-3\">Theophrastaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-140\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clavija membranacea<\/td><td class=\"column-3\">Theophrastaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-141\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clidemia sprucei<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362552<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-142\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia alata<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">7\/15\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-143\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia bracteosa<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=168864&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">por el camino que lleva al Sendero Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-144\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia crenata<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=168871&amp;clid=0<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\">A 50 m del R\u00edo Los Cedros por el camino que lleva al Sendero Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-145\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia dixonii<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-146\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41545174<\/td><td class=\"column-2\">Clusia hydrogera<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-147\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia multiflora<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=168927&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">por el camino que lleva al Sendero Observatorio.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-148\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41205385<\/td><td class=\"column-2\">Clusia niambiensis<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-149\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia thurifera<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=168941&amp;clid=0<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\">Colecciones generales en bosque cerrado<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-150\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Clusia trochiformis<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-151\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cojoba arborea<\/td><td class=\"column-3\">Fabaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947141<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-152\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/148853668<\/td><td class=\"column-2\">Columnea albovinosa<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Clark et al. 2011<\/td><td class=\"column-9\">M. Freiberg 96216<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Type is from Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-153\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea angulata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Clark et. al. 2021<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2085457&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-154\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea angustata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364758<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-155\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea benthamiana<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg, 1997<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-156\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea byrsina<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">Freiberg, 1997; Schulte et al. 2014<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-157\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea byrsina (syn=Pentadenia byrsina)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-158\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41318179<\/td><td class=\"column-2\">Columnea ciliata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Clark, J. L. et al.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/673833<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-159\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9992974<\/td><td class=\"column-2\">Columnea eburnea (Dalbergaria)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-160\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea fimbricalyx<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Epiphyte-vine<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364848<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-161\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea katzensteinii<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362650<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-162\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea mastersonii<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=1959048&amp;clid=0<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-163\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea medicinalis<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/676988<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-164\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea minutiflora<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/677357<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-165\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47633802<\/td><td class=\"column-2\">Columnea picta<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364692<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-166\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Columnea spathulata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364685<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-167\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41238705<\/td><td class=\"column-2\">Columnea strigosa (syn=kucyniakii)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Epiphyte-vine<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362528<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-168\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Compsoneura sprucei<\/td><td class=\"column-3\">Myristicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6676097&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Y de la Cascada-Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-169\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Condaminea corymbosa<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-170\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Conostegia aff. centronioides<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-171\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Conostegia cuatrecasii<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-172\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Conostegia superba<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6505059&amp;clid=0<\/td><td class=\"column-10\">1\/1\/1998<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-173\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cordia colombiana<\/td><td class=\"column-3\">Boraginaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-174\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cordia mexiana<\/td><td class=\"column-3\">Boraginaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-175\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41495277<\/td><td class=\"column-2\">Corynaea crassa<\/td><td class=\"column-3\">Balanophoraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-176\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Coto shimbillo (old=Inga velutina)<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946759<\/td><td class=\"column-10\">4\/19\/2019<\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-177\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Couepia chrysocalyx<\/td><td class=\"column-3\">Chrysobalanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946760<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-178\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Couepia sp.<\/td><td class=\"column-3\">Chrysobalanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-179\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Coussapoa contorta<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377163&amp;clid=0<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-180\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Critoniopsis occidentalis<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-181\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/52303640<\/td><td class=\"column-2\">Crotalaria sp.<\/td><td class=\"column-3\">Fab-Faboideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat: E. Obando<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-182\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48043041<\/td><td class=\"column-2\">Cuatresia harlingiana<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-183\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cuatresia physalana<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Orozco, 2011<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-184\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cupania aff. cinerea<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-185\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cupania cinerea<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-186\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cyathea caracasana<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377181&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-187\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cyathea halonata<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-188\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cyathea multiflora<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6237506&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">parcela permanente de inventario de una hect<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-189\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cyathea pallescens<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Medina<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377195&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-190\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9740117<\/td><td class=\"column-2\">Cyathea pilosissima<\/td><td class=\"column-3\">Cyatheaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-191\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Cybianthus humilis<\/td><td class=\"column-3\">Primulaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-192\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dacryodes chimantensis<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2952683<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Parcela permanente de inventario de una hect\u00e1rea de bosque. Note Bitty saysDistribution is wrong for this species<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-193\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dacryodes cupularis<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375858&amp;clid=0<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-194\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dacryodes olivifera<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729378<\/td><td class=\"column-10\">2\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-195\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dacryodes peruviana<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">7\/6\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-196\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dalbergaria albovinosa<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548106<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">TYPE Locality is Los Cedros; VU B1ab(iii). sendero observatorio (sw of lodge). Holotype: QCA M. FREIBERG 96216<\/td><td class=\"column-12\">Holotype: QCA M. FREIBERG 96216<\/td>\n<\/tr>\n<tr class=\"row-197\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Damburneya purpurea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Medina et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375864&amp;clid=0<\/td><td class=\"column-10\">6\/20\/2019<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-198\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9740135<\/td><td class=\"column-2\">Danaea nodosa (syn=Danaea erecta)<\/td><td class=\"column-3\">Marattiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-199\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Daphnopsis equatorialis<\/td><td class=\"column-3\">Thymelaeaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947480<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-200\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Daphnopsis grandis<\/td><td class=\"column-3\">Thymelaeaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-201\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dendropanax cf. macrophyllum<\/td><td class=\"column-3\">Araliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-202\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Deprea sachapapa<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947110<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-203\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Desmodium axillare<\/td><td class=\"column-3\">Fabaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-204\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41188672<\/td><td class=\"column-2\">Diastema affine<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364650<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-205\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Diastema racemiferum<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">Clark, J. L. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-206\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/51637749<\/td><td class=\"column-2\">Diastema scabrum<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362680<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero de las Cascadas (1-2 km west of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-207\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dicksonia sellowiana<\/td><td class=\"column-3\">Dicksoniaceae<\/td><td class=\"column-4\">Tree Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=141891&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Colecciones generales de \u00e1rea en regeneraci\u00f3n con presencia de gramalote<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-208\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Diplazium aberrans (Callipteris aberrans)<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Pacheco, 1999<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-209\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9748931<\/td><td class=\"column-2\">Diplazium divisissimum<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-210\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9811958<\/td><td class=\"column-2\">Diplazium lindbergii<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-211\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9811897<\/td><td class=\"column-2\">Diplazium megaphyllum (syn=Diplazium macrophyllum)<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=145142&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Colecciones generales de \u00e1rea en regeneraci\u00f3n con presencia de gramalote.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-212\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9992608<\/td><td class=\"column-2\">Diplazium rivale (syn=Callipteris rivalis)<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-213\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Diplazium roemerianum<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6289289&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero y de la cascada - estacion<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-214\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Diplazium venulosum<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=145204&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Colecciones generales de \u00e1rea en regeneraci\u00f3n con presencia de gramalote<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-215\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Diplazium wilsonii<\/td><td class=\"column-3\">Athyriaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947423<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Y de la Cascada - Estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-216\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47629674<\/td><td class=\"column-2\">Drymonia brochidodroma<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/677249<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-217\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Drymonia chiribogana<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364635<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Main trail<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-218\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Drymonia collegarum<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Clark, 2009<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362447<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Type Locality; IT: Drymonia collegarum J.L. Clark &amp; J.R. Clark. - Selbyana 29(2): 152\u2013156, f. 1a\u2013e, 2a, c\u2013e. 2008[2009]. (7 Jan 2009) (Selbyana) (MO\/BC:MO-2325604\/A:6257772)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-219\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Drymonia coriaceae (syn=Erythranthus coriaceus)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362476<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-220\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Drymonia rhodoloma<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-221\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/148837223<\/td><td class=\"column-2\">Drymonia tenuis<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Epiphytic herbaceous vine<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Freiberg<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/679614<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-222\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41188534<\/td><td class=\"column-2\">Drymonia teucheri (Alloplectus)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/679820<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-223\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Drymonia warszewicziana<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364856<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-224\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Dussia lehmannii<\/td><td class=\"column-3\">Fab-Faboideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-225\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Elaeagia karstenii<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947356<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-226\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Elaeagia utilis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-227\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Elaphoglossum decoratum<\/td><td class=\"column-3\">Dryopteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5748160&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">along trail from the station down to Rio Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-228\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9812382<\/td><td class=\"column-2\">Elaphoglossum lloense<\/td><td class=\"column-3\">Dryopteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-229\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9752695<\/td><td class=\"column-2\">Elaphoglossum peltatum<\/td><td class=\"column-3\">Dryopteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2083016&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-230\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Elaphoglossum pteropodum <\/td><td class=\"column-3\">Dryopteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/612438<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-231\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9782137<\/td><td class=\"column-2\">Elaphoglossum sprucei<\/td><td class=\"column-3\">Dryopteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Note that in IUCN it is still listed as CR even though reevaluated more recently in Ecuador where endemic as EN<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-232\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Elaphoglossum tripartitum<\/td><td class=\"column-3\">Dryopteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/612624<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-233\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/52103073<\/td><td class=\"column-2\">Elephantopus mollis<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947143<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-234\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Endlicheria aff. tessmannii<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-235\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Endlicheria cf. chalisea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-236\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Endlicheria cf. sericea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-237\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Endlicheria cf. tessmannii<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-238\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Endlicheria formosa<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-239\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Endlicheria klugii<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-240\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Enterosora trifurcata (syn=Grammitis trifurcata)<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/613559<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-241\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/58461958<\/td><td class=\"column-2\">Erythrina edulis<\/td><td class=\"column-3\">Fab-Faboideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-242\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Erythrina megistophylla<\/td><td class=\"column-3\">Fab-Faboideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-243\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Erythrina schimpffii<\/td><td class=\"column-3\">Fab-Faboideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-244\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Erythroxylum cf. novogranatense<\/td><td class=\"column-3\">Erythroxylaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-245\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Erythroxylum macrophyllum<\/td><td class=\"column-3\">Erythroxylaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364681<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Main trail<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-246\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Eschweilera caudiculata<\/td><td class=\"column-3\">Lecythidaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729558<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-247\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Eschweilera integrifolia<\/td><td class=\"column-3\">Lecythidaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-248\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Eschweilera rimbachii<\/td><td class=\"column-3\">Lecythidaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377189&amp;clid=0<\/td><td class=\"column-10\">3\/23\/2022<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-249\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Eugenia cuspidifolia<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-250\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Eugenia florida<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=8157951&amp;clid=0<\/td><td class=\"column-10\">5\/24\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-251\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea aff. oblongifolia<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-252\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea calyptrata<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5824451&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero a Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-253\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea cf. miconioides<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-254\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea flavicans<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-255\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea fragrans<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-256\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea glandulosa<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-257\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea langlassei<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">8\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-258\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea oblongifolia<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/724389<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-259\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea occidentalis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Medina<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/101221543<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-260\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Faramea ramosiana<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947411<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero a Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-261\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus andicola<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-262\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus brevibracteata<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Medina<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377314&amp;clid=0<\/td><td class=\"column-10\">11\/26\/2020<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-263\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus caldasiana<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">12\/15\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-264\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus calimana<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729560<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-265\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus citrifolia (syn=subandina)<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947074<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Y de la Cascada<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-266\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus cotopaxiensis<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-267\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus cuatrecasana<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/644058<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-268\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus dulciaria<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-269\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus macbridei<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-270\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus maxima<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-271\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus mutisii<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729564<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-272\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus sibundoya<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-273\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus tonduzii<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729383<\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-274\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ficus trianae<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-275\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Freziera reticulata<\/td><td class=\"column-3\">Theaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-276\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48829092<\/td><td class=\"column-2\">Fuchsia macrostigma<\/td><td class=\"column-3\">Onagraceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Kay, A. 2013<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-277\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Garcinia macrophylla<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375838&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-278\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/58423664<\/td><td class=\"column-2\">Garcinia madruno<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-279\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus atrolimbus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Herbarios ecuatorianos: QCA (HT)<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-280\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus corallinus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6559625&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-281\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus crispus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364697<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-282\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus giganteus=lateralis<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362522<\/td><td class=\"column-10\">4\/302004 as lateralis<\/td><td class=\"column-11\">Type locality is Los Cedros <\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-283\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41238349<\/td><td class=\"column-2\">Gasteranthus imbaburensis<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">Los Cedros Endemic<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548302<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Type locality is Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-284\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47864109<\/td><td class=\"column-2\">Gasteranthus lateralus (syn=Gasteranthus giganteus)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548300<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Type locality is Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-285\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48836031<\/td><td class=\"column-2\">Gasteranthus leopardus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548305<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Type locality is Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-286\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus pansamalanus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2082446&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-287\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus quitensis<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/685687<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-288\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gasteranthus trifoliatus<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. <\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548319<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Type locality is Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-289\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Geissanthus aff. pinchinchana<\/td><td class=\"column-3\">Primulaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-290\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Geissanthus cf. longistamineus<\/td><td class=\"column-3\">Primulaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-291\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Geonoma undata<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/515271<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-292\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117467460<\/td><td class=\"column-2\">Geonoma venosa<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">(CR)<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic to Los Cedros<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946750<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Endemic to Los Cedros. Sendaro a Bracilargo. Preliminary IUCN listing as CR: Couvreur, T. L. P., and A. Cosiaux. 2021. IUCN SSC Palm Specialist Group. IUCN, Gland, Switzerland. and Couvreur, T. L., N. Jijon, R. Mont\u00fafar, P. A. Morales\u2010Morales, M. J. San\u00edn, J. C. Copete, A. Lozinguez, \u00c1. J. P\u00e9rez, and E. Beech. 2024. Diversity and conservation status of palms (Arecaceae) in two hotspots of biodiversity in Colombia and Ecuador. Plants, People, Planet.<br \/>\n<br \/>\n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-293\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gloeospermum longifolium<\/td><td class=\"column-3\">Violaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-294\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/42488340<\/td><td class=\"column-2\">Glossoloma herthae<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Clark, 2009<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/690776<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-295\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Glossoloma oblonicalyx see Alloplectis<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-296\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Glossoloma penduliflorum see Alloplectis<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-297\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/bit<\/td><td class=\"column-2\">Glossoloma purpureum<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg, 1997; Clark, 2009<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/676124<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail from the comunidad El Chontal to Los Cedros<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-298\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Glossoloma sprucei See Alloplectis<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-299\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Glossoloma subglabrum<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Clark, 2009<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2083924&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-300\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47777602<\/td><td class=\"column-2\">Grias theobromicarpa<\/td><td class=\"column-3\">Lecythidaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Read<\/td><td class=\"column-9\">https:\/\/www.inaturalist.org\/observations\/47777602<\/td><td class=\"column-10\"> <\/td><td class=\"column-11\">Recently described; tropicos lists as endagered EC and IUCN have not evaluated it: http:\/\/legacy.tropicos.org\/Name\/100363006?projectid=2<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-301\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guarea aff. macrophylla<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-302\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guarea cartaguenya<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">8\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-303\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guarea cf. pubescens<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-304\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guarea cf. subandina<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-305\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guarea kunthiana<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-306\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guarea purusana<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-307\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guatteria megalophylla<\/td><td class=\"column-3\">Annonaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/20\/2017<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-308\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guettarda crispiflora<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-309\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guettarda hirsuta<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-310\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41151799<\/td><td class=\"column-2\">Gurania eriantha<\/td><td class=\"column-3\">Cucurbitaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-311\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41370543<\/td><td class=\"column-2\">Gurania lobata<\/td><td class=\"column-3\">Cucurbitaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-312\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Gustavia dodsonii<\/td><td class=\"column-3\">Lecythidaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-313\">\n\t<td class=\"column-1\">https:\/\/www.flickr.com\/photos\/andreaskay\/8609619204\/in\/album-72157629132785818\/<\/td><td class=\"column-2\">Guzmania conglomerata<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Kay, A. 2013<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-314\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guzmania danielii<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S.et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-315\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guzmania harlingii<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S.et al.<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-316\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guzmania hitchcockiana<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=140655&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Colecciones generales en bosque secundario<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-317\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41542590<\/td><td class=\"column-2\">Guzmania jaramilloi<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">LC<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Brown, 2015<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946670<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-318\">\n\t<td class=\"column-1\">https:\/\/www.flickr.com\/photos\/andreaskay\/8584423267\/in\/album-72157629132785818\/<\/td><td class=\"column-2\">Guzmania lehmanniana<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Kay, A. 2013<\/td><td class=\"column-9\">Dalstr\u00f6m, S.et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-319\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guzmania squarrosa<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362486<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-320\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Guzmania testudinis<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Brown, 2015<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947408<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-321\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/51958594<\/td><td class=\"column-2\">Guzmania xanthobractea<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364886<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-322\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hedyosmum cuatrecazanum<\/td><td class=\"column-3\">Chloranthaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947026<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-323\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hedyosmum goudotianum var. goudotianum<\/td><td class=\"column-3\">Chloranthaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-324\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hedyosmum sp. (misid'd as H. dombeyanum, which occurs further South)<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6489594&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Potentially misidentified; not known in Ecuador acc. to Tropicos and iNAt.  Range is further south.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-325\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hedyosum racemosum<\/td><td class=\"column-3\">Chloranthaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Medina<\/td><td class=\"column-9\">specimen Medina<\/td><td class=\"column-10\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375886&amp;clid=0<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-326\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Heisteria acuminata<\/td><td class=\"column-3\">Olacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-327\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Heisteria concinna<\/td><td class=\"column-3\">Olacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">2\/17\/2021<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-328\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Heisteria erythrocarpa<\/td><td class=\"column-3\">Olacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729381<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Tropicos lists as NT globally, but not in IUCN.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-329\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41543835<\/td><td class=\"column-2\">Heliconia aff. fragilis<\/td><td class=\"column-3\">Heliconiaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-330\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Heliconia impudica<\/td><td class=\"column-3\">Heliconiaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Mariscal et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=144437&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">por el camino que lleva al Sendero Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-331\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41543608<\/td><td class=\"column-2\">Heliconia latispatha<\/td><td class=\"column-3\">Heliconiaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-332\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Helicostylis tomentosa<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377263&amp;clid=0<\/td><td class=\"column-10\">1\/1\/1998<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-333\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Helicostylis tovarensis<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-334\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Helosis cayanensis<\/td><td class=\"column-3\">Balanophoraceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362566<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-335\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hieronyma alchorneoides<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6164673&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">parcela permanente de inventario de una hect<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-336\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hieronyma asperifolia<\/td><td class=\"column-3\">Pyllanthaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-337\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hieronyma macrocarpa<\/td><td class=\"column-3\">Pyllanthaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Medina<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7366435&amp;clid=0<\/td><td class=\"column-10\">2\/25\/2022<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-338\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hoffmannia cf. parviflora<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-339\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hoffmannia sp (misid'd as H. pedunculata, from Jamaica)<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6477179&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero el Inca; likely misidentified as H. penuculata is a species of Jamaica<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-340\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hoffmannia viridis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947470<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-341\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Huertea glandulosa<\/td><td class=\"column-3\">Tapisciaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947073<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-342\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hyeronima scabrida<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-343\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hymenophyllum fucoides<\/td><td class=\"column-3\">Hymenophyllaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947051<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-344\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Hyospathe elegans<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">12\/6\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-345\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ilex cf. yurumanguinis<\/td><td class=\"column-3\">Aquifoliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-346\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ilex laurina<\/td><td class=\"column-3\">Aquifoliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">8\/10\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-347\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ilex maxima<\/td><td class=\"column-3\">Aquifoliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947370<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Y de Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-348\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga aff. lallensis<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-349\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga aff. nobilis<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-350\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga aff. sapindoides<\/td><td class=\"column-3\">Fabaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-351\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga aff. villosissima<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-352\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga densiflora<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946752<\/td><td class=\"column-10\">5\/19\/2020<\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-353\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga lallensis<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">11\/19\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-354\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga nobilis<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Niell<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729356<\/td><td class=\"column-10\">11\/14\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-355\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga oerstediana<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377264&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-356\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga punctata<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-357\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga velutina<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5824229&amp;clid=0<\/td><td class=\"column-10\">3\/19\/2019<\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-358\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Inga villosissima<\/td><td class=\"column-3\">Fab-Mimosoideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-359\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Isertia laevis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-360\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Isertia pittieri<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947450<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-361\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Josemania truncata (syn=Tillandsia truncata)<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2110440&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-362\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Juanulloa pavonii (syn=Markea pavonii)<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-363\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41154227<\/td><td class=\"column-2\">Justicia pectoralis<\/td><td class=\"column-3\">Acanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-364\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Kohleria spicata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364703<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-365\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41251115<\/td><td class=\"column-2\">Kohleria villosa<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364880<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-366\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ladenbergia pavonii<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947407<\/td><td class=\"column-10\">2012 Ecuador, 4\/30\/2004 IUCN<\/td><td class=\"column-11\">Sendero a Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-367\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41154250<\/td><td class=\"column-2\">Langsdorffia hypogaea<\/td><td class=\"column-3\">Balanophoraceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-368\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Lasiacis nigra<\/td><td class=\"column-3\">Poaceae<\/td><td class=\"column-4\">Graminoid<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947100<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-369\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Leandra longicoma<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-370\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Leandra subseriata<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-371\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Lellingera<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/614453<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-372\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9993431<\/td><td class=\"column-2\">Lellingeria suspensa<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-373\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Licania cf. heteromorpha<\/td><td class=\"column-3\">Chrysobalanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-374\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Licaria cf. tomentosa<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-375\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9992549<\/td><td class=\"column-2\">Lomardium endiforme (syn=Blechnum ensiforme)<\/td><td class=\"column-3\">Blechnaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-376\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Lonchocarpus sp.<\/td><td class=\"column-3\">Fab-Faboideae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-377\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/148865124<\/td><td class=\"column-2\">Macleania bullata<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat Ulsterbotany<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-378\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Macleania ericae<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas<\/td><td class=\"column-9\">11\/21\/2018<\/td><td class=\"column-10\">11\/21\/2018<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Y de Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-379\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/42172089<\/td><td class=\"column-2\">Macleania pentaptera<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947362<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-380\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Macludrainia<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6244489&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">parcela permanente de inventario de una hect<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-381\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Macrocarpaea sodiroana<\/td><td class=\"column-3\">Gentianaceae<\/td><td class=\"column-4\">Herbaceous<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947428<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Y de la Cascada - Estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-382\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/40636025<\/td><td class=\"column-2\">Mandevilla callista<\/td><td class=\"column-3\">Apocynaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat: E. Obando<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-383\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Marcgravia umbellata<\/td><td class=\"column-3\">Marcgraviaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6489817&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-384\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Marila<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6639299&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">main trail<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-385\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Markea pavonii<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-386\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Matisia aff. bolivarii<\/td><td class=\"column-3\">Bombacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-387\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Matisia castano<\/td><td class=\"column-3\">Bombacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-388\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Mauria cf. heterophylla<\/td><td class=\"column-3\">Anacardiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-389\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meliosma arenosa<\/td><td class=\"column-3\">Sabiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947152<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-390\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meliosma frondosa<\/td><td class=\"column-3\">Sabiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5824372&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2020<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-391\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meliosma gracilis<\/td><td class=\"column-3\">Sabiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Cornejo, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947045<\/td><td class=\"column-10\">2012 Ecuador<\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-392\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meliosma novogranatensis<\/td><td class=\"column-3\">Sabiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364922<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-393\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meliosma occidentalis<\/td><td class=\"column-3\">Sabiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-394\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9993538<\/td><td class=\"column-2\">Meniscium macrophyllum<\/td><td class=\"column-3\">Thelypteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-395\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meriania finicola<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-396\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meriania maxima<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947404<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-397\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Meriania tomentosa<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729677<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-398\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Merostachys<\/td><td class=\"column-3\">Poaceae<\/td><td class=\"column-4\">Gramminoid<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6658249&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero observatorio (sw of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-399\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia aggregata<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-400\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia bracteolata<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-401\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia brevitheca<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck 2008; B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729357<\/td><td class=\"column-10\">2\/20\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-402\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia calvescens<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-403\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia cf. gracilis<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-404\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia cf. subnodosa<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-405\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia dapsiliflora<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-406\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia floribunda<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729555<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-407\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia loreyoides<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-408\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia neomicrantha (syn=Ossaea micrantha )<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-409\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Miconia theaezans<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-410\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Mikania sp.2<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-411\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Mollinedia sp.<\/td><td class=\"column-3\">Monimiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946692<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-412\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/148836560<\/td><td class=\"column-2\">Monnina<\/td><td class=\"column-3\">Polygalaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364777<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-413\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/109765661<\/td><td class=\"column-2\">Monopyle macrocarpa<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/677595<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-414\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Moquilea durifolia<\/td><td class=\"column-3\">Chrysobalanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">5\/26\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-415\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Morus insignis<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-416\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Myrcia aff. aliena<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-417\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Myrcia fallax<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">6\/4\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-418\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Myrcia splendens<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/4\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-419\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Myrica maxima=Calyptranthes maxima<\/td><td class=\"column-3\">Mrytaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">10\/29\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-420\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/50148233<\/td><td class=\"column-2\">Nasa aequatoriana<\/td><td class=\"column-3\">Loasaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">CR<\/td><td class=\"column-6\">CR<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Cooper, M.<\/td><td class=\"column-9\">https:\/\/www.inaturalist.org\/observations\/50148233<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Re-evaluated in 2012 in Ecuador and there upgrded to CR so CR everywhere as endemic<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-421\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Naucleopsis naga<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-422\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Naucleopsis ulei<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-423\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra acutifolia<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">2\/13\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-424\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra aff. guadaripo<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-425\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra aff. laurel<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-426\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra aff. membranacea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-427\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra aff. parviflora<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-428\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra aff. purpurea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-429\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra guadaripo<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">1\/1\/1998<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-430\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra lineatifolia<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Maybe misid'd have my doubts about this one-it is an east side species<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-431\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra lucida<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-432\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra membranacea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/25\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-433\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra obtusata<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/4\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-434\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra purpurea<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729556<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-435\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Nectandra reticulata<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">1\/23\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-436\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Neomirandea<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Liana<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947385<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-437\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9993671<\/td><td class=\"column-2\">Nephrolepis cordifolia<\/td><td class=\"column-3\">Nephrolepidaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-438\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9805233<\/td><td class=\"column-2\">Niphidium crassifolium<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-439\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Notopleura cf. longipedunculoides<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Shrub<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-440\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Notopleura corniculata<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947455<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-441\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Notopleura macrophylla<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946664<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-442\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ochroma pyramidale<\/td><td class=\"column-3\">Bombacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">12\/31\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-443\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea aff. cernua<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-444\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea aff. floccifera<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-445\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea aff. heterochroma<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-446\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea aff. oblonga<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-447\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea Aubl. Sp. 1<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-448\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea cernua<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-449\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea cuneifolia<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-450\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea floccifera<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377275&amp;clid=0<\/td><td class=\"column-10\">Parcela temporal<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-451\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea floribunda<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">5\/25\/2021<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-452\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea insularis<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">4\/20\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-453\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea macrophylla<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-454\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea oblonga<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-455\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea stenoneura<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/21\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-456\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ocotea stuebelii<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">9\/9\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-457\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117469034<\/td><td class=\"column-2\">Oenocarpus minor<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">(LC)<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-9\">Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">LC according to tropicos but not in IUCN or Ecuador red list<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-458\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9797283<\/td><td class=\"column-2\">Oleandra articulata<\/td><td class=\"column-3\">Oleandraceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-459\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Oreopanax confusus<\/td><td class=\"column-3\">Araliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-460\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Oreopanax ecuadorensis<\/td><td class=\"column-3\">Araliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">LC<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\">have my doubts about this one too-out of range<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-461\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ossaea cf. micrantha<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-462\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ossaea micrantha<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-463\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ossaea robusta<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-464\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Otoba gordoniifolia<\/td><td class=\"column-3\">Myristicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946756<\/td><td class=\"column-10\">8\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-465\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Otoba novogranatensis<\/td><td class=\"column-3\">Myristicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Medina<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375695&amp;clid=0<\/td><td class=\"column-10\">5\/5\/2020<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-466\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ouratea weberbaueri<\/td><td class=\"column-3\">Ochnaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-467\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pachira patinoi<\/td><td class=\"column-3\">Bombacaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">10\/26\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-468\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea acanthacea<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-469\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea amethystina<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-470\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea andrei<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Medina,<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729559<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-471\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea chimboracensis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-472\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41855167<\/td><td class=\"column-2\">Palicourea demissa<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947030<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-473\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea drewiana<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946745<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-474\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea gibbosa<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-475\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea guianense<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6218670&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">parcela permanente de inventario de una hect<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-476\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea longistipula<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947381<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Y de Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-477\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea lugoana<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946676<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-478\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea pyramidalis (syn= Palicourea gibbosa)<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362609<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"> Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-479\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea sodiroi<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947036<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-480\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea stipularis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2108<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-481\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Palicourea thyrsiflora<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2108<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-482\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9748766<\/td><td class=\"column-2\">Parablechnum stipitellatum (syn=Blechnum stipitellatum)<\/td><td class=\"column-3\">Blechnaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-483\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Paradrymonia splendens<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548399<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Holotype: QCA M. FREIBERG 96008<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-484\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47864135<\/td><td class=\"column-2\">Passiflora arbelaezii<\/td><td class=\"column-3\">Passifloraceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">iNat-Read<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-485\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9752648<\/td><td class=\"column-2\">Pecluma eurybasis<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-486\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pentadenia byrsina see Columnea brysina<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-487\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pentadenia lutea (=Columnea angustata)<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Freiberg M. 1997. The gesneriad flora of the Los Cedros Biological Reserve, northwest Ecuador, part 2: New species in Alloplectus, Dalbergaria, Paradrymonia and Pentadenia (Gesneriaceae). Phyton-International Journal of Experimental Botany 37(1): 133-140.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/548424<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Holotype: QCA M. FREIBERG 96019<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-488\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pentadenia spathulata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-489\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pentagonia clementinensis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947117<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-490\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pentagonia macrophylla<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2108<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-491\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/55563527<\/td><td class=\"column-2\">Peperomia crispa<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat: A. Nelson<\/td><td class=\"column-9\">verified by Guido Mathieu, Peperomia taxonomist<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Libro Rojo says 3populstions, byt Mathieu says there are about 15 observations of this species now<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-492\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Perebea angustifolia<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-493\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Perebea xanthochyma<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2952632<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-494\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Perebia angustifolia<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-495\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Persea aff. areolatocostae<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-496\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Persea americana (syn=Persea nubigena)<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">2\/14\/2017<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-497\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Persea areolatocostae<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-498\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Persea povedae<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375679&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-499\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Persea pseudofasciculata<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008; Mariscal, Thomas et. al. 2021<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729562<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-500\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Persea rigens<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377198&amp;clid=0<\/td><td class=\"column-10\">2\/15\/2017<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-501\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9734889<\/td><td class=\"column-2\">Philodendron fibrosum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-502\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Philodendron oligospermum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947053<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-503\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Philodendron schmidtiae<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Croat, 2013<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362668<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-504\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/39265379<\/td><td class=\"column-2\">Philodendron verrucosum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-505\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9992399<\/td><td class=\"column-2\">Phlebodium areolatum (syn=Phlebodium pseudoaureum)<\/td><td class=\"column-3\">Polypodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-506\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Phlegmariurus linifolius<\/td><td class=\"column-3\">Lycopodiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">M. Freiberg<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/618962<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-507\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Physalis pubescens<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al.<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6532728&amp;clid=0<\/td><td class=\"column-10\">2\/14\/2017<\/td><td class=\"column-11\">sendero el observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-508\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pilea ceratocalyx<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947116<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-509\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pilea cf. hirsuta<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946651<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-510\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pilea jamesoniana<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947031<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-511\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pilea myriantha<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5824524&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-512\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper aduncum<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-513\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper aff. nudibracteatun<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-514\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/52093930<\/td><td class=\"column-2\">Piper appendiculatum<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat: N. Peel<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-515\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper cf. imperiale<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-516\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper fuliginosum<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-517\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper imperiale<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-518\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper obliquum<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-519\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper spoliatum<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-520\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper squamulosum<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-521\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piper tuberculatum (syn=Piper obliquum)<\/td><td class=\"column-3\">Piperaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-522\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Piptocoma discolor<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-523\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/148897028<\/td><td class=\"column-2\">Pitcairnia arcuata<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Ulsterbotany<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">3\/5\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-524\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia bifurcatispina<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic to Los Cedros<\/td><td class=\"column-8\">Fern\u00e1ndez-Fern\u00e1ndez, 2015; Leon-Yanez et al. , 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Type Locality; Los Cedros Endemic<\/td><td class=\"column-12\">Pitcairnia bifurcatispina Manzan. &amp; W. Till. - Jewels of the Jungle: Bromeliaceae of Ecuador 2: 396\u2013397, f. 24a\u2013e. 2005. (6 Jan 2005) (Jewels Jungle: Bromeliaceae Ecuador) (MO\/BC:MO-934107\/A:5874023)<\/td>\n<\/tr>\n<tr class=\"row-525\">\n\t<td class=\"column-1\">https:\/\/www.flickr.com\/photos\/andreaskay\/8518477500\/in\/album-72157629132785818\/<\/td><td class=\"column-2\">Pitcairnia dendroidea<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Kay, A. 2013<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-526\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia dolichopetala<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Name does not exist in Tropicos<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-527\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia elliptica<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">CR<\/td><td class=\"column-6\">CR<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2961891<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">NA as endangered<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-528\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia elongata<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-529\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia ferrell-ingramiae<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Luther, 1997<\/td><td class=\"column-9\">S. Dalstr\u00f6m, S. Ingram &amp; K. Ferrell-Ingram 2236<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\">Los Cedros is Type Locality<\/td><td class=\"column-12\">Journal of the Bromeliad Society 47(5): 231. 1997.<\/td>\n<\/tr>\n<tr class=\"row-530\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia guzmanioides<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">Clark, J. L.et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-531\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41620041<\/td><td class=\"column-2\">Pitcairnia nigra<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Brown, 2015<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946629<\/td><td class=\"column-10\">5\/18\/2009<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-532\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia palmoides<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">specimen Dalstr\u00f6m<\/td><td class=\"column-9\">Dalstr\u00f6m, S. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-533\">\n\t<td class=\"column-1\">https:\/\/www.flickr.com\/photos\/andreaskay\/8439785337<\/td><td class=\"column-2\">Pitcairnia sp. <\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">terrestrial<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Kay, A. 2013<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-534\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pitcairnia spectabilis<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2380758<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero de las cascadas (1-2 km west of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-535\">\n\t<td class=\"column-1\">https:\/\/www.flickr.com\/photos\/andreaskay\/6800930834<\/td><td class=\"column-2\">Pitcairnia squarrosa var. colorata<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">LC<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Kay, A. 2013<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-536\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pleuranthodendron lindenii<\/td><td class=\"column-3\">Salicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-537\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pleurothyrium aff. giganthum<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-538\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pleurothyrium cinereum<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">8\/25\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-539\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pleurothyrium giganthum<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-540\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pleurothyrium glabritepalum<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">9\/2\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-541\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Plinia<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Medina<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7377236&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-542\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Plukenetia volubilis<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-543\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41539445<\/td><td class=\"column-2\">Plumbago zeylanica<\/td><td class=\"column-3\">Plumbaginaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-544\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9812158<\/td><td class=\"column-2\">Polytaenium lineatum<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-545\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Posoqueria coriacea<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-546\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pourouma minor<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2961032<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Parcela permanente de inventario de una hect\u00e1rea de bosque<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-547\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pouteria torta<\/td><td class=\"column-3\">Sapotaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-548\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47627766<\/td><td class=\"column-2\">Prestoea acuminata<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">12\/6\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-549\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Protium aff. nodulosum<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-550\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Protium amazonicum (syn=Protium fimbriatum)<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5825333&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2108<\/td><td class=\"column-11\">Sendero Y de la Cascada-Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-551\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Protium colombianum<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729379<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-552\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Protium ecuadorense<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375699&amp;clid=0<\/td><td class=\"column-10\">2\/15\/2023<\/td><td class=\"column-11\">Parcela temporal<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-553\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Protium sp.<\/td><td class=\"column-3\">Burseraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-554\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/101369343<\/td><td class=\"column-2\">Psammisia aberrans<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-555\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48847619<\/td><td class=\"column-2\">Psammisia debilis<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">iNat: N. Peel<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-556\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41685869<\/td><td class=\"column-2\">Psammisia flaviflora<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat: E. Obando<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">11\/22\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-557\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47634428<\/td><td class=\"column-2\">Psammisia guianensis<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-558\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47635454<\/td><td class=\"column-2\">Psammisia sodiroi<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946762<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-559\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pseudolmedia macrophylla<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-560\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pseudolmedia rigida<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/19\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-561\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psidium sp.<\/td><td class=\"column-3\">Myrtaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-562\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria aff. hazenii<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Shrub<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-563\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria cf. steyermarkii<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-564\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria flaviflora<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">2\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-565\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria gentryi<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729348<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-566\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria montivaga<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947384<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Y de Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-567\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria paeonia<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-568\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria pilosa<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/19\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-569\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Psychotria rimbachii<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946749<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">NA as endangered<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-570\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9752677<\/td><td class=\"column-2\">Pteridium arachnoideum (syn=Pteris arachnoidea)<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-571\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47636133<\/td><td class=\"column-2\">Pteris altissima<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-572\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pteris boliviensis<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=969054&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero de las Cascadas (1-2 km west of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-573\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Pteris consanguinea<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947414<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero a Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-574\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Quararibea aff. asterolepis<\/td><td class=\"column-3\">Malvaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-575\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Quararibea casasecae<\/td><td class=\"column-3\">Malvaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Thomas &amp; Vandegrift, 2016<\/td><td class=\"column-9\">D. Simba<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-576\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Quararibea wittii<\/td><td class=\"column-3\">Malvaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-577\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9812337<\/td><td class=\"column-2\">Radiovittaria gardneriana<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6298332&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-578\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/bit<\/td><td class=\"column-2\">Renealmia sessilifolia<\/td><td class=\"column-3\">Zingiberaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">LC<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Vargas et al.<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946638<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-579\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Rhodostemonodaphne cyclops<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">4\/14\/2021<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-580\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Rhodostemonodaphne kunthiana<\/td><td class=\"column-3\">Lauraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729678<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-581\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Rhynchospora orbigniana<\/td><td class=\"column-3\">Cyperaceae<\/td><td class=\"column-4\">Graminoid<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946660<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-582\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ruagea glabra<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-583\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ruagea pubescens<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">10\/17\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-584\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Ruagea trisperma<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-585\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Rudgea pendula<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947439<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Y de la Cascada - Estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-586\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9813141<\/td><td class=\"column-2\">Saccoloma domingense<\/td><td class=\"column-3\">Dennstaedtiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-587\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9813001<\/td><td class=\"column-2\">Saccoloma inaequale<\/td><td class=\"column-3\">Dennstaedtiaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-588\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Salacia cordata<\/td><td class=\"column-3\">Celastraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-589\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Salacia impressifolia<\/td><td class=\"column-3\">Celastraceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362504<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-590\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Salvia florida<\/td><td class=\"column-3\">Lamiaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947461<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-591\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sapium marmieri<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-592\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sapium stylare<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-593\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Schefflera lasiogyne<\/td><td class=\"column-3\">Araliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6639255&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero de las cascadas, w of lodge<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-594\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Schoenobiblus daphnoides<\/td><td class=\"column-3\">Thymelaeaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729352<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-595\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Schradera marginalis<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364832<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-596\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sciadophyllum<\/td><td class=\"column-3\">Araliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen A. Mariscal et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/101047102<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">A 50 m del Rio Los Cedros por el camino que lleva al Sendero Obsrvatorio.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-597\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117469595<\/td><td class=\"column-2\">Sciodaphyllum lasiogyne<\/td><td class=\"column-3\">Araliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic?<\/td><td class=\"column-8\">iNat: Thomas Couvreur<\/td><td class=\"column-9\">ID by Pete Lowry and Carolos Rodriguez<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-598\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Scleria neogranatensis<\/td><td class=\"column-3\">Cyperaceae<\/td><td class=\"column-4\">Graminoid<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen A. Mariscal et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=144371&amp;clid=0<\/td><td class=\"column-10\">1\/8\/2020<\/td><td class=\"column-11\">Colecciones generales en bosque secundario.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-599\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9995077<\/td><td class=\"column-2\">Selaginella anceps<\/td><td class=\"column-3\">Selaginellaceae<\/td><td class=\"column-4\">Fern-ally<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-600\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Senna dariensis<\/td><td class=\"column-3\">Fab-Caesalpiniaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-601\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Simarouba amara<\/td><td class=\"column-3\">Simaroubaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2961209<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-602\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Siparuna aspera<\/td><td class=\"column-3\">Monimiacaea<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-603\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Siparuna guajalitensis<\/td><td class=\"column-3\">Monimiacaea<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">near<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947354<\/td><td class=\"column-10\">4\/30\/2004<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Y de Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-604\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Siparuna guianensis<\/td><td class=\"column-3\">Monimiacaea<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6415224&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-605\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Siparuna laurifolia<\/td><td class=\"column-3\">Siparunaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-606\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Siparuna salvioides<\/td><td class=\"column-3\">Siparunaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=8149284&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-607\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Siparuna stellulata<\/td><td class=\"column-3\">Monimiacaea<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947479<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-608\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41151661<\/td><td class=\"column-2\">Sisyrinchium micranthum<\/td><td class=\"column-3\">Iridaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">iNat-Policha<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-609\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sloanea cf. grandiflora<\/td><td class=\"column-3\">Elaeocarpaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-610\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sloanea sp. 1<\/td><td class=\"column-3\">Elaeocarpaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-611\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sloanea sp. 2<\/td><td class=\"column-3\">Elaeocarpaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-612\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9735796<\/td><td class=\"column-2\">Socratea rostrata<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">2\/25\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-613\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum aff. circinatum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-614\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum aphyodendron<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947398<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero a Bracilargo.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-615\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum aturense<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947113<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-616\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum cf. circinatum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-617\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum clathratum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6574266&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2020<\/td><td class=\"column-11\">endero y de la cascada - estaci<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-618\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum cucullatum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947115<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-619\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum lepidotum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=5764306&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-620\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Solanum umbellatum<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947133<\/td><td class=\"column-10\">9\/2\/2022<\/td><td class=\"column-11\">Sendero Estaci\u00f3n - Bracilargo.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-621\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sorocea jaramilloi<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947159<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-622\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sorocea steinbachii<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-623\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Souroubea<\/td><td class=\"column-3\">Marcgraviaceae<\/td><td class=\"column-4\">Vine\/Liana<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\"><\/td><td class=\"column-8\">M. Freiberg<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/669483<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-624\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sphaeradenia garciae subsp. caudrosii<\/td><td class=\"column-3\">Cylanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947120<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-625\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41856157<\/td><td class=\"column-2\">Sphaeradenia sp.<\/td><td class=\"column-3\">Cylanthaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-626\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Sphyrospermum cordifolium<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">M. Freiberg<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/542722<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-627\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Spigelia hamelioides<\/td><td class=\"column-3\">Loganiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=1974944&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero de las Cascadas (1-2 km west of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-628\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Spirotheca awadendron<\/td><td class=\"column-3\">Bombacaeae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729382<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-629\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/55563513<\/td><td class=\"column-2\">Stenospermation<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat: A. Nelson<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-630\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Stenospermation latifolium<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Epiphyte-Vine<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">clark-specimen<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364838<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Observatorio (SW of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-631\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Stenospermation sodiroanum<\/td><td class=\"column-3\">Araceae<\/td><td class=\"column-4\">Epiphyte-Vine<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">clark-specimen<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362578<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-632\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Stephanopodium angulatum<\/td><td class=\"column-3\">Dichapetalaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=7375848&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2021<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-633\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Stephanopodium longipedicellatum<\/td><td class=\"column-3\">Dichapetalaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">EN<\/td><td class=\"column-6\">EN<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">10\/10\/2021<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-634\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9993882<\/td><td class=\"column-2\">Sticherus bifidus<\/td><td class=\"column-3\">Gleicheniaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-635\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41151748<\/td><td class=\"column-2\">Stromanthe stromanthoides<\/td><td class=\"column-3\">Marantaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-636\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Stylogyne ambigua (syn=Geissanthus)<\/td><td class=\"column-3\">Myrsinaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-637\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Stylogyne venezuelana (syn=Stylogyne micrantha)<\/td><td class=\"column-3\">Myrsinaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-638\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Styrax weberbaueri<\/td><td class=\"column-3\">Styracaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-639\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Symplocos fuliginosa<\/td><td class=\"column-3\">Symplocaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">8\/19\/2020<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-640\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tabernaemontana sp.<\/td><td class=\"column-3\">Apocynaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-641\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Talauma cf. gilbertoi<\/td><td class=\"column-3\">Magnoliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-642\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Talisia cerasina<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen B. Medina<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/729380<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-643\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Talisia cf. nervosa<\/td><td class=\"column-3\">Sapindaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-644\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tapirira guianensis<\/td><td class=\"column-3\">Anacardiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6375968&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-645\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9995285<\/td><td class=\"column-2\">Tectaria sp.<\/td><td class=\"column-3\">Tectariaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-646\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tetrorchidium andinum<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947482<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero El Inca - R\u00edo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-647\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tetrorchidium euryphyllum<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-648\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tetrorchidium macrophyllum<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-649\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tetrorchidium rubrivenium<\/td><td class=\"column-3\">Euphorbiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6254004&amp;clid=0<\/td><td class=\"column-10\">6\/12\/2020<\/td><td class=\"column-11\">sendero el inca - ri\u00ado<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-650\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Thelypteris<\/td><td class=\"column-3\">Thelypteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-651\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Theobroma cacao<\/td><td class=\"column-3\">Malvaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6488489&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Inca - R\u00edo.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-652\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Thibaudia harlingii<\/td><td class=\"column-3\">Ericaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">DD<\/td><td class=\"column-6\">DD<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6544880&amp;clid=0<\/td><td class=\"column-10\">11\/23\/2018<\/td><td class=\"column-11\">sendero observatorio (sw of lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-653\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/51164188<\/td><td class=\"column-2\">Tilesia baccata<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">iNat: N. Peel<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-654\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/41543397<\/td><td class=\"column-2\">Tillandsia cyanea (Syn=Wallasia)<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NT<\/td><td class=\"column-6\">NT<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Policha, 2012<\/td><td class=\"column-9\">Dalstr\u00f6m, S.<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-655\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tillandsia pretiosa<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">VU<\/td><td class=\"column-6\">VU<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947442<\/td><td class=\"column-10\">4\/30\/2003<\/td><td class=\"column-11\">Sendero Y de la Cascada - Estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-656\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tillandsia truncata<\/td><td class=\"column-3\">Bromeliaceae<\/td><td class=\"column-4\">Epihyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2362549<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge).<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-657\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tocoyena pittieri<\/td><td class=\"column-3\">Rubiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/18\/2021<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-658\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Topobea dodsonorum<\/td><td class=\"column-3\">Melastomataceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-659\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tournefortia cf. ramosissima<\/td><td class=\"column-3\">Boraginaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-660\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Tradescantia zanonia<\/td><td class=\"column-3\">Commelinaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947029<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero El Oso<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-661\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trema micrantha<\/td><td class=\"column-3\">Cannabaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-662\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/109769557<\/td><td class=\"column-2\">Trianaea nobilis<\/td><td class=\"column-3\">Solanaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">Specimen Clark<\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=2083648&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Sendero Camino del Oso (north of Lodge)<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-663\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trichantha ciliata see Columnea ciliata<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-664\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trichilia glabra<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Peck, 2008<\/td><td class=\"column-9\">Jos\u00e9 Homero Vargas L\u00f3pez<\/td><td class=\"column-10\">7\/4\/2019<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-665\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trichilia septentrionalis<\/td><td class=\"column-3\">Meliaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-666\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trichodrymonia hypocyrta<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Epiphyte<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2364605<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">Main trail<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-667\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trichodrymonia splendens<\/td><td class=\"column-3\">Gesneriaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">endemic<\/td><td class=\"column-8\">specimen Clark<\/td><td class=\"column-9\">Clark, J. L. et al.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-668\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/9994241<\/td><td class=\"column-2\">Triplophyllum sp.<\/td><td class=\"column-3\">Tectariaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat-Roy<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-669\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Trophis racemosa<\/td><td class=\"column-3\">Moraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-670\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Turpinia occidentalis (syn=Staphylea )<\/td><td class=\"column-3\">Staphyleacae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">specimen Vargas et al<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2952651<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Parcela permanente de inventario de una hect\u00e1rea de bosque, Sendero Y de la Cascada-Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-671\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/48823089<\/td><td class=\"column-2\">Urceolina <\/td><td class=\"column-3\">Amaryllidaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">iNat: N. Peel<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-672\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Urera aff. caracasana<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-673\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/109771825<\/td><td class=\"column-2\">Urera baccifera<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947419<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero a Bracilargo<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-674\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Urera caracasana<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-675\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Urera verrucosa<\/td><td class=\"column-3\">Urticaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946681<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n.<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-676\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Utricularia alpina<\/td><td class=\"column-3\">Lentibulariaceae<\/td><td class=\"column-4\">Herb<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Freiberg, M.<\/td><td class=\"column-9\">https:\/\/bioweb.bio\/portal\/QCAZ\/Especimen\/555114<\/td><td class=\"column-10\">12\/1\/2016<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-677\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Vasconcellea quercifolia<\/td><td class=\"column-3\">Caricaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">https:\/\/bndb.sisbioecuador.bio\/bndb\/collections\/individual\/index.php?occid=6462896&amp;clid=0<\/td><td class=\"column-10\"><\/td><td class=\"column-11\">sendero el observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-678\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Vernonanthura patens<\/td><td class=\"column-3\">Asteraceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-679\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Virola aff. sebifera<\/td><td class=\"column-3\">Myristicaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-680\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Vismia lauriformis<\/td><td class=\"column-3\">Clusiaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">10\/8\/2014<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-681\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Vittaria sp.<\/td><td class=\"column-3\">Pteridaceae<\/td><td class=\"column-4\">Fern<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">specimen Endara<\/td><td class=\"column-9\">Endara, L.<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-682\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Weigeltia cf. goudotiana<\/td><td class=\"column-3\">Myrsinaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-683\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Weinmannia balbisiana<\/td><td class=\"column-3\">Cunoniaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Wilson &amp; Rhemtella 2018<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-684\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/47628204<\/td><td class=\"column-2\">Wercklea ferox<\/td><td class=\"column-3\">Malvaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-685\">\n\t<td class=\"column-1\">https:\/\/www.inaturalist.org\/observations\/117468743<\/td><td class=\"column-2\">Wettinia oxycarpa<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">(NT)<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobandoa &amp; also Thomas Couvreur and Nicol\u00e1s Zapata (PUCE Quito, IRD<\/td><td class=\"column-10\">5\/23\/2022<\/td><td class=\"column-11\">NT according to Tropicos but not in IUCN or Ecuador Red Lost<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-686\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Wettinia quinaria<\/td><td class=\"column-3\">Arecaceae<\/td><td class=\"column-4\">Palm<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\">5\/23\/2022<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-687\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Witheringia coccoloboides<\/td><td class=\"column-3\">Solanaceeae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2947123<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Sendero El Observatorio<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-688\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Zanthoxylum mauriifolium<\/td><td class=\"column-3\">Rutaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">NE<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-689\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Zanthoxylum sp.<\/td><td class=\"column-3\">Rutaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">?<\/td><td class=\"column-8\">Mariscal, Thomas et. al. 2022<\/td><td class=\"column-9\">Jos\u00e9 Homero, Defas, Danilo Simba, Ana Mariscal, Rocio Manobando<\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<tr class=\"row-690\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">Zygia coccinea<\/td><td class=\"column-3\">Fabaceae<\/td><td class=\"column-4\">Woody<\/td><td class=\"column-5\">NE<\/td><td class=\"column-6\">LC<\/td><td class=\"column-7\">no<\/td><td class=\"column-8\">Specimen Vargas et al. <\/td><td class=\"column-9\">http:\/\/legacy.tropicos.org\/Specimen\/2946683<\/td><td class=\"column-10\">6\/12\/2018<\/td><td class=\"column-11\">Alrededores de la estaci\u00f3n<\/td><td class=\"column-12\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-4{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-4 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-4{width:100% !important;order : 0;}.fusion-builder-column-4 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-4{width:100% !important;order : 0;}.fusion-builder-column-4 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-3{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5975","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/pages\/5975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/comments?post=5975"}],"version-history":[{"count":13,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/pages\/5975\/revisions"}],"predecessor-version":[{"id":6535,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/pages\/5975\/revisions\/6535"}],"wp:attachment":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/media?parent=5975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}