{"id":5833,"date":"2024-04-01T14:24:39","date_gmt":"2024-04-01T14:24:39","guid":{"rendered":"https:\/\/reservaloscedros.org\/?p=5833"},"modified":"2024-04-01T14:24:44","modified_gmt":"2024-04-01T14:24:44","slug":"rescue-and-first-aid-workshop-for-forest-rangers-2","status":"publish","type":"post","link":"https:\/\/reservaloscedros.org\/es\/2024\/04\/01\/rescue-and-first-aid-workshop-for-forest-rangers-2\/","title":{"rendered":"Taller de rescate y primeros auxilios para guardabosques"},"content":{"rendered":"<p>En el marco del curso de formaci\u00f3n de guardabosques organizado por la Estaci\u00f3n Cient\u00edfica Los Cedros, dirigido a comuneros y comuneras del Valle de Los Manduriacos. Se desarroll\u00f3 un taller certificado de rescate y primeros auxilios agrestes a cargo de la Junta Provincial de Cruz Roja Imbabura, del 22 al 25 de febrero.<!--more--><\/p>\n<p><img decoding=\"async\" class=\"lazyload  wp-image-5809 aligncenter\" src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1.jpg\" data-orig-src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1.jpg\" alt=\"\" width=\"613\" height=\"613\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27613%27%20height%3D%27613%27%20viewBox%3D%270%200%20613%20613%27%3E%3Crect%20width%3D%27613%27%20height%3D%27613%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-12x12.jpg 12w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-66x66.jpg 66w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-150x150.jpg 150w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-200x200.jpg 200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-300x300.jpg 300w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-400x400.jpg 400w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1-600x600.jpg 600w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-1.jpg 768w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 613px) 100vw, 613px\" \/><\/p>\n<p>El curso abord\u00f3 diversas tem\u00e1ticas con pertinencia a la realidad de la zona, enfocado principalmente en responder a emergencias relacionadas con la labor de los guardabosques y los posibles riesgos que se pueden presentar dentro del bosque, as\u00ed como en las comunidades.<\/p>\n<p>Fue una jornada exhaustiva pero absolutamente enriquecedora, fusionando la teor\u00eda y la pr\u00e1ctica cada uno de los participantes fue desarrollando habilidades para una labor tan importante como la de atender de manera oportuna y efectiva las emergencias que ponen en riesgo la vida. En el taller se prioriz\u00f3 el trabajo en equipo y la respuesta efectiva bajo presi\u00f3n, a fin de alinearse con la realidad de las emergencias.<\/p>\n<p><img decoding=\"async\" class=\"lazyload wp-image-5822 aligncenter\" src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-1024x576.jpg\" data-orig-src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-1024x576.jpg\" alt=\"\" width=\"503\" height=\"283\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27503%27%20height%3D%27283%27%20viewBox%3D%270%200%20503%20283%27%3E%3Crect%20width%3D%27503%27%20height%3D%27283%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-18x10.jpg 18w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-200x113.jpg 200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-300x169.jpg 300w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-400x225.jpg 400w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-600x338.jpg 600w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-768x432.jpg 768w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-800x450.jpg 800w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-1024x576.jpg 1024w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-1200x675.jpg 1200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411-1536x864.jpg 1536w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/1708722125411.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 503px) 100vw, 503px\" \/><\/p>\n<p><img decoding=\"async\" class=\"lazyload  wp-image-5820 aligncenter\" src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1.png\" data-orig-src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1.png\" alt=\"\" width=\"497\" height=\"373\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27497%27%20height%3D%27373%27%20viewBox%3D%270%200%20497%20373%27%3E%3Crect%20width%3D%27497%27%20height%3D%27373%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-16x12.png 16w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-200x150.png 200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-300x225.png 300w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-400x300.png 400w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-600x450.png 600w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-768x576.png 768w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1-800x600.png 800w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1.png 1024w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 497px) 100vw, 497px\" \/><\/p>\n<p>De esta manera estamos contribuyendo a promover una cultura de prevenci\u00f3n y a gestionar las capacidades de las comunidades del \u00e1rea del Bosque Protector Los Cedros para prevenir y atender emergencias a trav\u00e9s de primeros auxilios b\u00e1sicos. Con la finalidad de garantizar la seguridad y bienestar de quienes habitan las comunidades, as\u00ed como a sus visitantes tanto a turistas como estudiantes, investigadores y cient\u00edficos.<\/p>\n<p><img decoding=\"async\" class=\"lazyload  wp-image-5811 aligncenter\" src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3.jpg\" data-orig-src=\"http:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27450%27%20viewBox%3D%270%200%20600%20450%27%3E%3Crect%20width%3D%27600%27%20height%3D%27450%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3-16x12.jpg 16w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3-200x150.jpg 200w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3-300x225.jpg 300w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3-400x300.jpg 400w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3-600x450.jpg 600w, https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/boletin7-3.jpg 768w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>En el marco del curso de formaci\u00f3n de guardabosques organizado por la Estaci\u00f3n Cient\u00edfica Los Cedros, dirigido a comuneros y comuneras del Valle de Los Manduriacos. Se desarroll\u00f3 un taller certificado de rescate y primeros auxilios agrestes a cargo de la Junta Provincial de Cruz Roja Imbabura, del 22 al 25 de febrero.<\/p>","protected":false},"author":2,"featured_media":5820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"ppma_author":[43],"class_list":["post-5833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-loscedros"],"jetpack_featured_media_url":"https:\/\/reservaloscedros.org\/wp-content\/uploads\/2024\/02\/img-bol-7-1.png","jetpack_sharing_enabled":true,"authors":[{"term_id":43,"user_id":2,"is_guest":0,"slug":"monserratte","display_name":"Monserratte V\u00e1squez","avatar_url":"https:\/\/reservaloscedros.org\/wp-content\/litespeed\/avatar\/e3718edfb892b1f4be41e3839ec3f2f3.jpg?ver=1787798929","author_category":"","first_name":"Monserratte","last_name":"V\u00e1squez","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/posts\/5833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/comments?post=5833"}],"version-history":[{"count":1,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/posts\/5833\/revisions"}],"predecessor-version":[{"id":5834,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/posts\/5833\/revisions\/5834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/media\/5820"}],"wp:attachment":[{"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/media?parent=5833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/categories?post=5833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/tags?post=5833"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/reservaloscedros.org\/es\/wp-json\/wp\/v2\/ppma_author?post=5833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}